{"id":6417,"date":"2023-10-17T11:47:29","date_gmt":"2023-10-17T09:47:29","guid":{"rendered":"https:\/\/ese.energy\/?p=6417"},"modified":"2023-10-17T11:47:30","modified_gmt":"2023-10-17T09:47:30","slug":"the-benevento-company-clesi-acquires-former-prefabricated-mabo-buildings","status":"publish","type":"post","link":"https:\/\/ese.energy\/en\/the-benevento-company-clesi-acquires-former-prefabricated-mabo-buildings\/","title":{"rendered":"The Benevento company Clesi acquires former prefabricated Mabo buildings"},"content":{"rendered":"<style type=\"text\/css\"><\/style>\n<p>Clesi prefabbricati, a Benevento company specializing in industrialized construction, is growing through acquisitions. The company \u2013 which is headed by entrepreneurs Luigi, Sergio and Ettore Izzo di Montesarchio \u2013 has concluded an important consolidation and\u00a0business\u00a0development operation by acquiring a new production unit, formerly Mabo Prefabbricati, which is based in Supino, in the province of Frosinone. This is one of the most important acquisitions in the prefabricated sector carried out in recent years. [&#8230;]<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.breakinglatest.news\/business\/the-benevento-company-clesi-acquires-former-prefabricated-mabo-buildings\/\" target=\"_blank\" rel=\"noreferrer noopener\">Full Article<\/a><\/div>\n<\/div>\n\n\n\n<p>Source: <a href=\"https:\/\/www.breakinglatest.news\/\" target=\"_blank\" rel=\"noreferrer noopener\">BreakingLatest<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Clesi prefabbricati, a Benevento company specializing in industrialized construction, is growing through acquisitions. The company \u2013 which is headed by entrepreneurs Luigi, Sergio and Ettore Izzo di Montesarchio \u2013 has concluded an important consolidation and\u00a0business\u00a0development operation by acquiring a new production unit, formerly Mabo Prefabbricati, which is based in Supino, in the province of Frosinone&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":6375,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[96],"tags":[],"class_list":["post-6417","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The Benevento company Clesi acquires former prefabricated Mabo buildings - ESE<\/title>\n<meta name=\"description\" content=\"Clesi prefabbricati, a Benevento company specializing in industrialized construction, is growing through acquisitions. The company \u2013 which is headed by\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ese.energy\/en\/the-benevento-company-clesi-acquires-former-prefabricated-mabo-buildings\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Benevento company Clesi acquires former prefabricated Mabo buildings - ESE\" \/>\n<meta property=\"og:description\" content=\"Clesi prefabbricati, a Benevento company specializing in industrialized construction, is growing through acquisitions. The company \u2013 which is headed by\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ese.energy\/en\/the-benevento-company-clesi-acquires-former-prefabricated-mabo-buildings\/\" \/>\n<meta property=\"og:site_name\" content=\"ESE\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-17T09:47:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-17T09:47:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ese.energy\/wp-content\/uploads\/2023\/10\/Ese-breaking-latest-news.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"820\" \/>\n\t<meta property=\"og:image:height\" content=\"490\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ese.energy\\\/en\\\/the-benevento-company-clesi-acquires-former-prefabricated-mabo-buildings\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ese.energy\\\/en\\\/the-benevento-company-clesi-acquires-former-prefabricated-mabo-buildings\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/ese.energy\\\/en\\\/#\\\/schema\\\/person\\\/844297935a0e4624d310e8bd7a26a611\"},\"headline\":\"The Benevento company Clesi acquires former prefabricated Mabo buildings\",\"datePublished\":\"2023-10-17T09:47:29+00:00\",\"dateModified\":\"2023-10-17T09:47:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ese.energy\\\/en\\\/the-benevento-company-clesi-acquires-former-prefabricated-mabo-buildings\\\/\"},\"wordCount\":85,\"image\":{\"@id\":\"https:\\\/\\\/ese.energy\\\/en\\\/the-benevento-company-clesi-acquires-former-prefabricated-mabo-buildings\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ese.energy\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Ese-breaking-latest-news.webp\",\"articleSection\":[\"Press\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ese.energy\\\/en\\\/the-benevento-company-clesi-acquires-former-prefabricated-mabo-buildings\\\/\",\"url\":\"https:\\\/\\\/ese.energy\\\/en\\\/the-benevento-company-clesi-acquires-former-prefabricated-mabo-buildings\\\/\",\"name\":\"The Benevento company Clesi acquires former prefabricated Mabo buildings - ESE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ese.energy\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ese.energy\\\/en\\\/the-benevento-company-clesi-acquires-former-prefabricated-mabo-buildings\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ese.energy\\\/en\\\/the-benevento-company-clesi-acquires-former-prefabricated-mabo-buildings\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ese.energy\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Ese-breaking-latest-news.webp\",\"datePublished\":\"2023-10-17T09:47:29+00:00\",\"dateModified\":\"2023-10-17T09:47:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ese.energy\\\/en\\\/#\\\/schema\\\/person\\\/844297935a0e4624d310e8bd7a26a611\"},\"description\":\"Clesi prefabbricati, a Benevento company specializing in industrialized construction, is growing through acquisitions. The company \u2013 which is headed by\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ese.energy\\\/en\\\/the-benevento-company-clesi-acquires-former-prefabricated-mabo-buildings\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ese.energy\\\/en\\\/the-benevento-company-clesi-acquires-former-prefabricated-mabo-buildings\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ese.energy\\\/en\\\/the-benevento-company-clesi-acquires-former-prefabricated-mabo-buildings\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ese.energy\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Ese-breaking-latest-news.webp\",\"contentUrl\":\"https:\\\/\\\/ese.energy\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Ese-breaking-latest-news.webp\",\"width\":820,\"height\":490},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ese.energy\\\/en\\\/the-benevento-company-clesi-acquires-former-prefabricated-mabo-buildings\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ese.energy\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Benevento company Clesi acquires former prefabricated Mabo buildings\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ese.energy\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ese.energy\\\/en\\\/\",\"name\":\"ESE\",\"description\":\"Efficiency, Saving, Environment\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ese.energy\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ese.energy\\\/en\\\/#\\\/schema\\\/person\\\/844297935a0e4624d310e8bd7a26a611\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61e70981968290bcf644b8afc527be1fd8de96308004bf2d2b21e6b7dc780d5c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61e70981968290bcf644b8afc527be1fd8de96308004bf2d2b21e6b7dc780d5c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61e70981968290bcf644b8afc527be1fd8de96308004bf2d2b21e6b7dc780d5c?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/ese.energy\"],\"url\":\"https:\\\/\\\/ese.energy\\\/en\\\/author\\\/ese_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Benevento company Clesi acquires former prefabricated Mabo buildings - ESE","description":"Clesi prefabbricati, a Benevento company specializing in industrialized construction, is growing through acquisitions. The company \u2013 which is headed by","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ese.energy\/en\/the-benevento-company-clesi-acquires-former-prefabricated-mabo-buildings\/","og_locale":"en_US","og_type":"article","og_title":"The Benevento company Clesi acquires former prefabricated Mabo buildings - ESE","og_description":"Clesi prefabbricati, a Benevento company specializing in industrialized construction, is growing through acquisitions. The company \u2013 which is headed by","og_url":"https:\/\/ese.energy\/en\/the-benevento-company-clesi-acquires-former-prefabricated-mabo-buildings\/","og_site_name":"ESE","article_published_time":"2023-10-17T09:47:29+00:00","article_modified_time":"2023-10-17T09:47:30+00:00","og_image":[{"width":820,"height":490,"url":"https:\/\/ese.energy\/wp-content\/uploads\/2023\/10\/Ese-breaking-latest-news.webp","type":"image\/webp"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ese.energy\/en\/the-benevento-company-clesi-acquires-former-prefabricated-mabo-buildings\/#article","isPartOf":{"@id":"https:\/\/ese.energy\/en\/the-benevento-company-clesi-acquires-former-prefabricated-mabo-buildings\/"},"author":{"name":"admin","@id":"https:\/\/ese.energy\/en\/#\/schema\/person\/844297935a0e4624d310e8bd7a26a611"},"headline":"The Benevento company Clesi acquires former prefabricated Mabo buildings","datePublished":"2023-10-17T09:47:29+00:00","dateModified":"2023-10-17T09:47:30+00:00","mainEntityOfPage":{"@id":"https:\/\/ese.energy\/en\/the-benevento-company-clesi-acquires-former-prefabricated-mabo-buildings\/"},"wordCount":85,"image":{"@id":"https:\/\/ese.energy\/en\/the-benevento-company-clesi-acquires-former-prefabricated-mabo-buildings\/#primaryimage"},"thumbnailUrl":"https:\/\/ese.energy\/wp-content\/uploads\/2023\/10\/Ese-breaking-latest-news.webp","articleSection":["Press"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/ese.energy\/en\/the-benevento-company-clesi-acquires-former-prefabricated-mabo-buildings\/","url":"https:\/\/ese.energy\/en\/the-benevento-company-clesi-acquires-former-prefabricated-mabo-buildings\/","name":"The Benevento company Clesi acquires former prefabricated Mabo buildings - ESE","isPartOf":{"@id":"https:\/\/ese.energy\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ese.energy\/en\/the-benevento-company-clesi-acquires-former-prefabricated-mabo-buildings\/#primaryimage"},"image":{"@id":"https:\/\/ese.energy\/en\/the-benevento-company-clesi-acquires-former-prefabricated-mabo-buildings\/#primaryimage"},"thumbnailUrl":"https:\/\/ese.energy\/wp-content\/uploads\/2023\/10\/Ese-breaking-latest-news.webp","datePublished":"2023-10-17T09:47:29+00:00","dateModified":"2023-10-17T09:47:30+00:00","author":{"@id":"https:\/\/ese.energy\/en\/#\/schema\/person\/844297935a0e4624d310e8bd7a26a611"},"description":"Clesi prefabbricati, a Benevento company specializing in industrialized construction, is growing through acquisitions. The company \u2013 which is headed by","breadcrumb":{"@id":"https:\/\/ese.energy\/en\/the-benevento-company-clesi-acquires-former-prefabricated-mabo-buildings\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ese.energy\/en\/the-benevento-company-clesi-acquires-former-prefabricated-mabo-buildings\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ese.energy\/en\/the-benevento-company-clesi-acquires-former-prefabricated-mabo-buildings\/#primaryimage","url":"https:\/\/ese.energy\/wp-content\/uploads\/2023\/10\/Ese-breaking-latest-news.webp","contentUrl":"https:\/\/ese.energy\/wp-content\/uploads\/2023\/10\/Ese-breaking-latest-news.webp","width":820,"height":490},{"@type":"BreadcrumbList","@id":"https:\/\/ese.energy\/en\/the-benevento-company-clesi-acquires-former-prefabricated-mabo-buildings\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ese.energy\/en\/"},{"@type":"ListItem","position":2,"name":"The Benevento company Clesi acquires former prefabricated Mabo buildings"}]},{"@type":"WebSite","@id":"https:\/\/ese.energy\/en\/#website","url":"https:\/\/ese.energy\/en\/","name":"ESE","description":"Efficiency, Saving, Environment","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ese.energy\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/ese.energy\/en\/#\/schema\/person\/844297935a0e4624d310e8bd7a26a611","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/61e70981968290bcf644b8afc527be1fd8de96308004bf2d2b21e6b7dc780d5c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/61e70981968290bcf644b8afc527be1fd8de96308004bf2d2b21e6b7dc780d5c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/61e70981968290bcf644b8afc527be1fd8de96308004bf2d2b21e6b7dc780d5c?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/ese.energy"],"url":"https:\/\/ese.energy\/en\/author\/ese_admin\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/ese.energy\/wp-content\/uploads\/2023\/10\/Ese-breaking-latest-news.webp",820,490,false],"thumbnail":["https:\/\/ese.energy\/wp-content\/uploads\/2023\/10\/Ese-breaking-latest-news-150x150.webp",150,150,true],"medium":["https:\/\/ese.energy\/wp-content\/uploads\/2023\/10\/Ese-breaking-latest-news-300x179.webp",300,179,true],"medium_large":["https:\/\/ese.energy\/wp-content\/uploads\/2023\/10\/Ese-breaking-latest-news-768x459.webp",768,459,true],"large":["https:\/\/ese.energy\/wp-content\/uploads\/2023\/10\/Ese-breaking-latest-news.webp",820,490,false],"gs-tiny":["https:\/\/ese.energy\/wp-content\/uploads\/2023\/10\/Ese-breaking-latest-news.webp",50,30,false],"xl":["https:\/\/ese.energy\/wp-content\/uploads\/2023\/10\/Ese-breaking-latest-news.webp",820,490,false],"xxl":["https:\/\/ese.energy\/wp-content\/uploads\/2023\/10\/Ese-breaking-latest-news.webp",820,490,false],"xxxl":["https:\/\/ese.energy\/wp-content\/uploads\/2023\/10\/Ese-breaking-latest-news.webp",820,490,false],"xxxxl":["https:\/\/ese.energy\/wp-content\/uploads\/2023\/10\/Ese-breaking-latest-news.webp",820,490,false],"xxxxxl":["https:\/\/ese.energy\/wp-content\/uploads\/2023\/10\/Ese-breaking-latest-news.webp",820,490,false],"1536x1536":["https:\/\/ese.energy\/wp-content\/uploads\/2023\/10\/Ese-breaking-latest-news.webp",820,490,false],"2048x2048":["https:\/\/ese.energy\/wp-content\/uploads\/2023\/10\/Ese-breaking-latest-news.webp",820,490,false],"post-thumbnail":["https:\/\/ese.energy\/wp-content\/uploads\/2023\/10\/Ese-breaking-latest-news.webp",820,490,false],"small-thumb":["https:\/\/ese.energy\/wp-content\/uploads\/2023\/10\/Ese-breaking-latest-news-55x55.webp",55,55,true],"square-thumb":["https:\/\/ese.energy\/wp-content\/uploads\/2023\/10\/Ese-breaking-latest-news-250x250.webp",250,250,true],"blog-masonry-thumb":["https:\/\/ese.energy\/wp-content\/uploads\/2023\/10\/Ese-breaking-latest-news-580x390.webp",580,390,true],"project-thumb":["https:\/\/ese.energy\/wp-content\/uploads\/2023\/10\/Ese-breaking-latest-news-580x460.webp",580,460,true],"project-masonry-thumb":["https:\/\/ese.energy\/wp-content\/uploads\/2023\/10\/Ese-breaking-latest-news-580x347.webp",580,347,true],"masonry-thumb":["https:\/\/ese.energy\/wp-content\/uploads\/2023\/10\/Ese-breaking-latest-news.webp",820,490,false],"full-thumb":["https:\/\/ese.energy\/wp-content\/uploads\/2023\/10\/Ese-breaking-latest-news.webp",820,490,false],"project-full-thumb":["https:\/\/ese.energy\/wp-content\/uploads\/2023\/10\/Ese-breaking-latest-news.webp",820,490,false],"full-masonry-thumb":["https:\/\/ese.energy\/wp-content\/uploads\/2023\/10\/Ese-breaking-latest-news.webp",820,490,false]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/ese.energy\/en\/author\/ese_admin\/"},"uagb_comment_info":0,"uagb_excerpt":"Clesi prefabbricati, a Benevento company specializing in industrialized construction, is growing through acquisitions. The company \u2013 which is headed by entrepreneurs Luigi, Sergio and Ettore Izzo di Montesarchio \u2013 has concluded an important consolidation and\u00a0business\u00a0development operation by acquiring a new production unit, formerly Mabo Prefabbricati, which is based in Supino, in the province of Frosinone....","_links":{"self":[{"href":"https:\/\/ese.energy\/en\/wp-json\/wp\/v2\/posts\/6417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ese.energy\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ese.energy\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ese.energy\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ese.energy\/en\/wp-json\/wp\/v2\/comments?post=6417"}],"version-history":[{"count":2,"href":"https:\/\/ese.energy\/en\/wp-json\/wp\/v2\/posts\/6417\/revisions"}],"predecessor-version":[{"id":6419,"href":"https:\/\/ese.energy\/en\/wp-json\/wp\/v2\/posts\/6417\/revisions\/6419"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ese.energy\/en\/wp-json\/wp\/v2\/media\/6375"}],"wp:attachment":[{"href":"https:\/\/ese.energy\/en\/wp-json\/wp\/v2\/media?parent=6417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ese.energy\/en\/wp-json\/wp\/v2\/categories?post=6417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ese.energy\/en\/wp-json\/wp\/v2\/tags?post=6417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}